{"id":147,"date":"2011-10-13T03:34:00","date_gmt":"2011-10-13T02:34:00","guid":{"rendered":"http:\/\/micoulou.info\/wp\/index.php\/2011\/10\/13\/nouvelles-6\/"},"modified":"2011-10-13T03:34:00","modified_gmt":"2011-10-13T02:34:00","slug":"nouvelles-6","status":"publish","type":"post","link":"https:\/\/www.micoulou-photos.com\/index.php\/2011\/10\/13\/nouvelles-6\/","title":{"rendered":"Nouvelles"},"content":{"rendered":"<p>Bon, vous allez me dire, en 3 jours, que s&rsquo;est il pass\u00e9 pour que je redonne des nouvelles de nouveaux&#8230;<br \/>En fait, j&rsquo;ai eu un entretien hier, et j&rsquo;ai sign\u00e9&#8230; Un peu dans la continuit\u00e9 de ce que j&rsquo;ai fait au figaro et au studio photo, mais avec plus de dev, donc ce que je cherchais&#8230; Avec un peu de videos, d&rsquo;imagerie, de gestion de projet&#8230; Je me dis que finalement, toutes ces docs lues sur differentes technologies n&rsquo;ont pas servies \u00e0 rien (notamment MongoDb). On verra comment \u00e7a se passe mais si \u00e7a se passe bien \u00e7a sera pour quelques ann\u00e9es, \u00e7a me fait bizarre d&rsquo;avoir sign\u00e9 pour autant de temps&#8230; A paris, je n&rsquo;avais pas prevu de rester plus d&rsquo;un an, l\u00e0 ce serait pour +-3 ans, voire plus, vais-je tenir? Si je peux voyager entre, \u00e7a devrait pouvoir se faire m\u00eame si mes amis et ma famille en France et en europe vont me manquer&#8230;<br \/>&nbsp;Pour les jobs, j&rsquo;ai pas mal utilis\u00e9 les site monster,<a href=\"http:\/\/jooble-fr.com\/\">jobble<\/a> et joboom.<br \/>Aujourd&rsquo;hui, ouverture d&rsquo;un compte en banque canadien, avec RBC, c&rsquo;\u00e9tait conseill\u00e9 par PVTiste.net&#8230; Ca s&rsquo;est super bien pass\u00e9, et le banquier etait super sympa, un portugais avec qui on a discuter une bonne heure&#8230; Bon, j&rsquo;ai pris un compte de base, comme toute ces choses l\u00e0, ce n&rsquo;est pas donn\u00e9 au canada, j&rsquo;ai pris pour le d\u00e9but le compte de base limit\u00e9 \u00e0 15 transactions par mois, on verra comment \u00e7a se passe, mais si je veux ne pas trop consommer, \u00e7a devrait passer.<br \/>Je suis aussi repasser chez MEC m&rsquo;acheter un duvet pour dormir (car le miens n&rsquo;est pas vraiment chaud&#8230;), un oreill\u00e9 de camping et un manteau d&rsquo;hiver (encore une fois, taille enfant, les tailles adultes sont vraiments grandes ici&#8230;). D&rsquo;ailleurs, je verrais si ils sont vraiment plus chaud que ce qu&rsquo;on trouve en frace mais \u00e7a \u00e0 l&rsquo;air&#8230; Et les tailles enfant sont assez accessible en prix (une centaine de $CA) alors que les taille adultes montent facilement \u00e0 250-300$CA&#8230;.<br \/>Demain, je visite une coloc qui \u00e0 l&rsquo;air vraiment sympa, \u00e0 5 minutes de l\u00e0 o\u00f9 je suis et \u00e0 5 minutes de l\u00e0 o\u00f9 je vais bosser (en fait exactement au millieu) donc j&rsquo;espere que \u00e7a se passera bien.<br \/>Il ne me restera plus que les activit\u00e9 externes \u00e0 organiser : aikido, sorties avec PVTiste.net et meetup&#8230; Mais \u00e7a devrait bien se passer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bon, vous allez me dire, en 3 jours, que s&rsquo;est il pass\u00e9 pour que je redonne des nouvelles de nouveaux&#8230;En fait, j&rsquo;ai eu un entretien hier, et j&rsquo;ai sign\u00e9&#8230; Un peu dans la continuit\u00e9 de ce que j&rsquo;ai fait au figaro et au studio photo, mais avec plus de dev, donc ce que je cherchais&#8230; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-147","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nouvelles - Micoulou Photographie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.micoulou-photos.com\/index.php\/2011\/10\/13\/nouvelles-6\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouvelles - Micoulou Photographie\" \/>\n<meta property=\"og:description\" content=\"Bon, vous allez me dire, en 3 jours, que s&rsquo;est il pass\u00e9 pour que je redonne des nouvelles de nouveaux&#8230;En fait, j&rsquo;ai eu un entretien hier, et j&rsquo;ai sign\u00e9&#8230; Un peu dans la continuit\u00e9 de ce que j&rsquo;ai fait au figaro et au studio photo, mais avec plus de dev, donc ce que je cherchais&#8230; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.micoulou-photos.com\/index.php\/2011\/10\/13\/nouvelles-6\/\" \/>\n<meta property=\"og:site_name\" content=\"Micoulou Photographie\" \/>\n<meta property=\"article:published_time\" content=\"2011-10-13T02:34:00+00:00\" \/>\n<meta name=\"author\" content=\"micoulou\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"micoulou\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.micoulou-photos.com\\\/index.php\\\/2011\\\/10\\\/13\\\/nouvelles-6\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.micoulou-photos.com\\\/index.php\\\/2011\\\/10\\\/13\\\/nouvelles-6\\\/\"},\"author\":{\"name\":\"micoulou\",\"@id\":\"https:\\\/\\\/www.micoulou-photos.com\\\/#\\\/schema\\\/person\\\/6aedfe8ebe91da632f46e7c9d806a722\"},\"headline\":\"Nouvelles\",\"datePublished\":\"2011-10-13T02:34:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.micoulou-photos.com\\\/index.php\\\/2011\\\/10\\\/13\\\/nouvelles-6\\\/\"},\"wordCount\":418,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.micoulou-photos.com\\\/#organization\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.micoulou-photos.com\\\/index.php\\\/2011\\\/10\\\/13\\\/nouvelles-6\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.micoulou-photos.com\\\/index.php\\\/2011\\\/10\\\/13\\\/nouvelles-6\\\/\",\"url\":\"https:\\\/\\\/www.micoulou-photos.com\\\/index.php\\\/2011\\\/10\\\/13\\\/nouvelles-6\\\/\",\"name\":\"Nouvelles - Micoulou Photographie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.micoulou-photos.com\\\/#website\"},\"datePublished\":\"2011-10-13T02:34:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.micoulou-photos.com\\\/index.php\\\/2011\\\/10\\\/13\\\/nouvelles-6\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.micoulou-photos.com\\\/index.php\\\/2011\\\/10\\\/13\\\/nouvelles-6\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.micoulou-photos.com\\\/index.php\\\/2011\\\/10\\\/13\\\/nouvelles-6\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.micoulou-photos.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.micoulou-photos.com\\\/#website\",\"url\":\"https:\\\/\\\/www.micoulou-photos.com\\\/\",\"name\":\"Micoulou Photographie\",\"description\":\"Photographies, Visites virtuelles et formations par Mickael Minarie\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.micoulou-photos.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.micoulou-photos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.micoulou-photos.com\\\/#organization\",\"name\":\"Micoulou Photographie\",\"url\":\"https:\\\/\\\/www.micoulou-photos.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.micoulou-photos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.micoulou-photos.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-891667_552097324824916_1615181552_o-1.jpg?fit=643%2C722&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.micoulou-photos.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-891667_552097324824916_1615181552_o-1.jpg?fit=643%2C722&ssl=1\",\"width\":643,\"height\":722,\"caption\":\"Micoulou Photographie\"},\"image\":{\"@id\":\"https:\\\/\\\/www.micoulou-photos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.micoulou-photos.com\\\/#\\\/schema\\\/person\\\/6aedfe8ebe91da632f46e7c9d806a722\",\"name\":\"micoulou\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98f892eb7d267eab2faa437baa3edd708deaaa43929316c0cc7b751a04cb247b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98f892eb7d267eab2faa437baa3edd708deaaa43929316c0cc7b751a04cb247b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98f892eb7d267eab2faa437baa3edd708deaaa43929316c0cc7b751a04cb247b?s=96&d=mm&r=g\",\"caption\":\"micoulou\"},\"url\":\"https:\\\/\\\/www.micoulou-photos.com\\\/index.php\\\/author\\\/micoulou\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nouvelles - Micoulou Photographie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.micoulou-photos.com\/index.php\/2011\/10\/13\/nouvelles-6\/","og_locale":"fr_FR","og_type":"article","og_title":"Nouvelles - Micoulou Photographie","og_description":"Bon, vous allez me dire, en 3 jours, que s&rsquo;est il pass\u00e9 pour que je redonne des nouvelles de nouveaux&#8230;En fait, j&rsquo;ai eu un entretien hier, et j&rsquo;ai sign\u00e9&#8230; Un peu dans la continuit\u00e9 de ce que j&rsquo;ai fait au figaro et au studio photo, mais avec plus de dev, donc ce que je cherchais&#8230; [&hellip;]","og_url":"https:\/\/www.micoulou-photos.com\/index.php\/2011\/10\/13\/nouvelles-6\/","og_site_name":"Micoulou Photographie","article_published_time":"2011-10-13T02:34:00+00:00","author":"micoulou","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"micoulou","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.micoulou-photos.com\/index.php\/2011\/10\/13\/nouvelles-6\/#article","isPartOf":{"@id":"https:\/\/www.micoulou-photos.com\/index.php\/2011\/10\/13\/nouvelles-6\/"},"author":{"name":"micoulou","@id":"https:\/\/www.micoulou-photos.com\/#\/schema\/person\/6aedfe8ebe91da632f46e7c9d806a722"},"headline":"Nouvelles","datePublished":"2011-10-13T02:34:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.micoulou-photos.com\/index.php\/2011\/10\/13\/nouvelles-6\/"},"wordCount":418,"commentCount":0,"publisher":{"@id":"https:\/\/www.micoulou-photos.com\/#organization"},"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.micoulou-photos.com\/index.php\/2011\/10\/13\/nouvelles-6\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.micoulou-photos.com\/index.php\/2011\/10\/13\/nouvelles-6\/","url":"https:\/\/www.micoulou-photos.com\/index.php\/2011\/10\/13\/nouvelles-6\/","name":"Nouvelles - Micoulou Photographie","isPartOf":{"@id":"https:\/\/www.micoulou-photos.com\/#website"},"datePublished":"2011-10-13T02:34:00+00:00","breadcrumb":{"@id":"https:\/\/www.micoulou-photos.com\/index.php\/2011\/10\/13\/nouvelles-6\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.micoulou-photos.com\/index.php\/2011\/10\/13\/nouvelles-6\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.micoulou-photos.com\/index.php\/2011\/10\/13\/nouvelles-6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.micoulou-photos.com\/"},{"@type":"ListItem","position":2,"name":"Nouvelles"}]},{"@type":"WebSite","@id":"https:\/\/www.micoulou-photos.com\/#website","url":"https:\/\/www.micoulou-photos.com\/","name":"Micoulou Photographie","description":"Photographies, Visites virtuelles et formations par Mickael Minarie","publisher":{"@id":"https:\/\/www.micoulou-photos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.micoulou-photos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.micoulou-photos.com\/#organization","name":"Micoulou Photographie","url":"https:\/\/www.micoulou-photos.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.micoulou-photos.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.micoulou-photos.com\/wp-content\/uploads\/2020\/05\/cropped-891667_552097324824916_1615181552_o-1.jpg?fit=643%2C722&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.micoulou-photos.com\/wp-content\/uploads\/2020\/05\/cropped-891667_552097324824916_1615181552_o-1.jpg?fit=643%2C722&ssl=1","width":643,"height":722,"caption":"Micoulou Photographie"},"image":{"@id":"https:\/\/www.micoulou-photos.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.micoulou-photos.com\/#\/schema\/person\/6aedfe8ebe91da632f46e7c9d806a722","name":"micoulou","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/98f892eb7d267eab2faa437baa3edd708deaaa43929316c0cc7b751a04cb247b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/98f892eb7d267eab2faa437baa3edd708deaaa43929316c0cc7b751a04cb247b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/98f892eb7d267eab2faa437baa3edd708deaaa43929316c0cc7b751a04cb247b?s=96&d=mm&r=g","caption":"micoulou"},"url":"https:\/\/www.micoulou-photos.com\/index.php\/author\/micoulou\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7zKF4-2n","jetpack-related-posts":[{"id":84,"url":"https:\/\/www.micoulou-photos.com\/index.php\/2012\/10\/31\/one-month-of-woofing\/","url_meta":{"origin":147,"position":0},"title":"one month of woofing","author":"micoulou","date":"31 octobre 2012","format":false,"excerpt":"Cela fait un peu plus d'un an... Un moi \u00e0 sleeping lady farm en colombie britannique, en tant que \"helper\"...J'ai donc remasteris\u00e9 tous \u00e7a, avant de faire du menage dans mes rushs, exporter une version HD, essayer de corriger 2-3 petits trucs... Avec un macbook pro un peu plus rapide\u2026","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"https:\/\/www.micoulou-photos.com\/index.php\/category\/non-classe\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":141,"url":"https:\/\/www.micoulou-photos.com\/index.php\/2011\/10\/23\/une-semaine-de-boulot\/","url_meta":{"origin":147,"position":1},"title":"Une semaine de boulot","author":"micoulou","date":"23 octobre 2011","format":false,"excerpt":"J'ai commenc\u00e9 mon nouveau boulot cette semaine... Bon, \u00e7a fait du bien de se remettre dans le bain de l'informatique apr\u00e8s 9 mois, j'ai un peu perdu en vitesse mais pas en comp\u00e9tences... Le boulot n'est pas des plus interressant (une base \u00e0 mapper dans une autre) mais j'espere que\u2026","rel":"","context":"Dans &quot;voyage&quot;","block_context":{"text":"voyage","link":"https:\/\/www.micoulou-photos.com\/index.php\/category\/voyage\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":137,"url":"https:\/\/www.micoulou-photos.com\/index.php\/2011\/11\/19\/nouvelle-et-remise-en-question\/","url_meta":{"origin":147,"position":2},"title":"Nouvelle et remise en question","author":"micoulou","date":"19 novembre 2011","format":false,"excerpt":"Bon, cel\u00e0 fait quelques temps que les message etait tr\u00e8s g\u00e9n\u00e9raliste...Comme j'avais du le dire dans un precedent message, j'avais trouv\u00e9 un job... Ce que je n'avais pas dit, c'est que \u00e0 ce moment, j'avais d\u00e9j\u00e0 pass\u00e9 2 entretiens et que j'attendais les reponses, les 2 autres jobs me motivaient\u2026","rel":"","context":"Dans &quot;Canada&quot;","block_context":{"text":"Canada","link":"https:\/\/www.micoulou-photos.com\/index.php\/category\/canada\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":135,"url":"https:\/\/www.micoulou-photos.com\/index.php\/2011\/12\/15\/nouvelles-5\/","url_meta":{"origin":147,"position":3},"title":"Nouvelles","author":"micoulou","date":"15 d\u00e9cembre 2011","format":false,"excerpt":"Bonjour \u00e0 tous,Il m'est arriv\u00e9 un certain nombre de chose depuis fin octobre et la premiere perte de mon emploi... EH, oui, j'ai recherch\u00e9 un emploi pendant 1 mois avec un CV qui n'allait pas du tout... Je retravaille maintenant, toujours dans la premiere boite, bon l'instant c'est encore recent\u2026","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"https:\/\/www.micoulou-photos.com\/index.php\/category\/non-classe\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/1.bp.blogspot.com\/-2yiLXpD3Mag\/TuTahGfsqSI\/AAAAAAAAqZ4\/JJZIO-2s1Do\/s320\/SDIM0087.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4885,"url":"https:\/\/www.micoulou-photos.com\/index.php\/2018\/12\/02\/les-aventures-dun-aspiboy-vol-1\/","url_meta":{"origin":147,"position":4},"title":"Les aventures d&rsquo;un aspiboy &#8211; Vol 1","author":"micoulou","date":"2 d\u00e9cembre 2018","format":false,"excerpt":"Je vais essayer, une fois par mois, de vous raconter quelques unes de mes \u201caventures\u201d, juste pour pouvoir de mon cot\u00e9 prendre un peu de recul sur ces situations\u2026\u2028Cette semaine a \u00e9t\u00e9 particuli\u00e8rement charg\u00e9e\u2026\u2028On commence donc par le d\u00e9but, je signe il y a 2 mois une formation Photoshop Element\u2026","rel":"","context":"Dans &quot;Asperger&quot;","block_context":{"text":"Asperger","link":"https:\/\/www.micoulou-photos.com\/index.php\/category\/asperger\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.micoulou-photos.com\/wp-content\/uploads\/2018\/12\/DSC02876-Modifier.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.micoulou-photos.com\/wp-content\/uploads\/2018\/12\/DSC02876-Modifier.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.micoulou-photos.com\/wp-content\/uploads\/2018\/12\/DSC02876-Modifier.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.micoulou-photos.com\/wp-content\/uploads\/2018\/12\/DSC02876-Modifier.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.micoulou-photos.com\/wp-content\/uploads\/2018\/12\/DSC02876-Modifier.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":3033,"url":"https:\/\/www.micoulou-photos.com\/index.php\/2017\/02\/05\/arrive-a-muret\/","url_meta":{"origin":147,"position":5},"title":"arriv\u00e9 a muret","author":"micoulou","date":"5 f\u00e9vrier 2017","format":false,"excerpt":"Petite aventure pour ce deuxi\u00e8me helpx de cette ann\u00e9e, apr\u00e8s une alerte rouge de temp\u00eate en partant de bordeaux, j'ai pu quand rejoindre mon train qui n'avait qu'un quart d'heure de retard... Dans le train, je me suis rendu compte que j'ai oubli\u00e9\u00a0 un des 2 appareils\u00a0 photo que j'avais\u2026","rel":"","context":"Dans &quot;voyage&quot;","block_context":{"text":"voyage","link":"https:\/\/www.micoulou-photos.com\/index.php\/category\/voyage\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.micoulou-photos.com\/wp-content\/uploads\/2017\/02\/tmp_7082-LRM_EXPORT_20170205_222016847481312.jpg?fit=1200%2C795&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.micoulou-photos.com\/wp-content\/uploads\/2017\/02\/tmp_7082-LRM_EXPORT_20170205_222016847481312.jpg?fit=1200%2C795&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.micoulou-photos.com\/wp-content\/uploads\/2017\/02\/tmp_7082-LRM_EXPORT_20170205_222016847481312.jpg?fit=1200%2C795&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.micoulou-photos.com\/wp-content\/uploads\/2017\/02\/tmp_7082-LRM_EXPORT_20170205_222016847481312.jpg?fit=1200%2C795&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.micoulou-photos.com\/wp-content\/uploads\/2017\/02\/tmp_7082-LRM_EXPORT_20170205_222016847481312.jpg?fit=1200%2C795&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.micoulou-photos.com\/index.php\/wp-json\/wp\/v2\/posts\/147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.micoulou-photos.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.micoulou-photos.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.micoulou-photos.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.micoulou-photos.com\/index.php\/wp-json\/wp\/v2\/comments?post=147"}],"version-history":[{"count":0,"href":"https:\/\/www.micoulou-photos.com\/index.php\/wp-json\/wp\/v2\/posts\/147\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.micoulou-photos.com\/index.php\/wp-json\/wp\/v2\/media?parent=147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.micoulou-photos.com\/index.php\/wp-json\/wp\/v2\/categories?post=147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.micoulou-photos.com\/index.php\/wp-json\/wp\/v2\/tags?post=147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}